{"id":1168,"date":"2026-01-06T11:18:41","date_gmt":"2026-01-06T10:18:41","guid":{"rendered":"https:\/\/omkafe.com\/barista\/"},"modified":"2026-08-31T15:42:57","modified_gmt":"2026-08-31T13:42:57","slug":"professionista","status":"publish","type":"page","link":"https:\/\/omkafe.com\/en\/professionista\/","title":{"rendered":"Professional"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1168","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Professional - Omkaf\u00e8<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/omkafe.com\/en\/professionista\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Professional - Omkaf\u00e8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/omkafe.com\/en\/professionista\/\" \/>\n<meta property=\"og:site_name\" content=\"Omkaf\u00e8\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/omkafe\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T13:42:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/omkafe.com\\\/en\\\/professionista\\\/\",\"url\":\"https:\\\/\\\/omkafe.com\\\/en\\\/professionista\\\/\",\"name\":\"Professional - Omkaf\u00e8\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/omkafe.com\\\/en\\\/#website\"},\"datePublished\":\"2026-01-06T10:18:41+00:00\",\"dateModified\":\"2026-08-31T13:42:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/omkafe.com\\\/en\\\/professionista\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/omkafe.com\\\/en\\\/professionista\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/omkafe.com\\\/en\\\/professionista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/omkafe.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Professional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/omkafe.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/omkafe.com\\\/en\\\/\",\"name\":\"Omkaf\u00e8\",\"description\":\"Torrefazione a Riva del Garda dal 1947\",\"alternateName\":\"Omkaf\u00e8\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/omkafe.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Professional - Omkaf\u00e8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/omkafe.com\/en\/professionista\/","og_locale":"en_US","og_type":"article","og_title":"Professional - Omkaf\u00e8","og_url":"https:\/\/omkafe.com\/en\/professionista\/","og_site_name":"Omkaf\u00e8","article_publisher":"https:\/\/www.facebook.com\/omkafe\/","article_modified_time":"2026-08-31T13:42:57+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/omkafe.com\/en\/professionista\/","url":"https:\/\/omkafe.com\/en\/professionista\/","name":"Professional - Omkaf\u00e8","isPartOf":{"@id":"https:\/\/omkafe.com\/en\/#website"},"datePublished":"2026-01-06T10:18:41+00:00","dateModified":"2026-08-31T13:42:57+00:00","breadcrumb":{"@id":"https:\/\/omkafe.com\/en\/professionista\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/omkafe.com\/en\/professionista\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/omkafe.com\/en\/professionista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/omkafe.com\/en\/"},{"@type":"ListItem","position":2,"name":"Professional"}]},{"@type":"WebSite","@id":"https:\/\/omkafe.com\/en\/#website","url":"https:\/\/omkafe.com\/en\/","name":"Omkaf\u00e8","description":"Torrefazione a Riva del Garda dal 1947","alternateName":"Omkaf\u00e8","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/omkafe.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/omkafe.com\/en\/wp-json\/wp\/v2\/pages\/1168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/omkafe.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/omkafe.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/omkafe.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/omkafe.com\/en\/wp-json\/wp\/v2\/comments?post=1168"}],"version-history":[{"count":0,"href":"https:\/\/omkafe.com\/en\/wp-json\/wp\/v2\/pages\/1168\/revisions"}],"wp:attachment":[{"href":"https:\/\/omkafe.com\/en\/wp-json\/wp\/v2\/media?parent=1168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}